{"id":38763,"date":"2021-02-24T12:15:37","date_gmt":"2021-02-24T10:15:37","guid":{"rendered":"https:\/\/factorialhr.com\/blog\/?p=38763"},"modified":"2025-06-02T02:43:31","modified_gmt":"2025-06-02T00:43:31","slug":"guia-de-offboarding","status":"publish","type":"post","link":"https:\/\/factorialhr.pt\/blog\/guia-de-offboarding\/","title":{"rendered":"Offboarding: Como despedir um funcion\u00e1rio? [+ Checklist em Excel]"},"content":{"rendered":"<p>Quando o RH contrata uma pessoa e acaba de fazer o <a href=\"https:\/\/factorialhr.pt\/blog\/software-onboarding\/\">onboarding<\/a> dela \u2026 o trabalho j\u00e1 est\u00e1 feito, certo? Na verdade, n\u00e3o. Muitas empresas n\u00e3o d\u00e3o tanta import\u00e2ncia ao <strong>processo de offboarding,<\/strong> e \u00e9 muito comum a \u00e1rea de Recursos Humanos focar apenas na parte em que o funcion\u00e1rio \u00e9, propriamente dito, um funcion\u00e1rio.<\/p>\n<p>No entanto, se o offboarding n\u00e3o for considerado algo fundamental no relacionamento com um funcion\u00e1rio, pode n\u00e3o ser feito de maneira adequada, e nesse caso a empresa estaria cometendo um erro grave. <strong>Despedir um funcion\u00e1rio<\/strong> \u00e9 um processo que deve ser igualmente pensado e planeado com cuidado. Afinal, a marca empregadora est\u00e1 em jogo a todo momento.<\/p>\n<p>Aqui, explicaremos exatamente <strong>o que \u00e9 offboarding e onboarding , por que s\u00e3o t\u00e3o importantes e quais s\u00e3o as etapas a seguir nestes processos.<\/strong><\/p>\n<p><strong>N\u00e3o quer ler o artigo, mas gostava de obter a lista de tarefas para realizar um bom processo de offboarding? \ud83d\udc47<\/strong><\/p>\n<p><span style=\"color: #0000ff;\"><strong><a href=\"#4\">\u2714\ufe0fDescarregue aqui o Guia de Offboarding gratuitamente<\/a><\/strong><\/span><br \/>\n* Inclui caixas de sele\u00e7\u00e3o, perguntas para a entrevista de despedimento e uma lista de invent\u00e1rio da empresa.<\/p>\n<ul>\n<li><a href=\"#1\">O que \u00e9 Offboarding?<\/a><\/li>\n<li><a href=\"#2\">Por que \u00e9 importante para as empresas?<\/a><\/li>\n<li><a href=\"#3\">Como despedir um funcion\u00e1rio: 11 etapas principais<\/a><\/li>\n<li><a href=\"#4\">Descarregar checklist de Offboarding<\/a><\/li>\n<li><a href=\"https:\/\/factorialhr.com\/blog\/?p=38763&amp;preview=true#4\">Ferramenta para melhorar o Onboarding e Offboarding na sua empresa<\/a><\/li>\n<\/ul>\n<h2><a name=\"1\"><\/a><strong>O que \u00e9 Offboarding?<\/strong><\/h2>\n<p>Despedir um funcion\u00e1rio \u00e9 necess\u00e1rio quando ele deixa a empresa, tanto volunt\u00e1ria quanto involuntariamente. Embora a r<a href=\"https:\/\/factorialhr.pt\/blog\/rotatividade-de-pessoal\/\">otatividade de pessoal<\/a> dentro de uma empresa possa ser normal, muitas vezes os <strong>departamentos de Recursos Humanos n\u00e3o est\u00e3o totalmente preparados para isso<\/strong> e n\u00e3o percebem a import\u00e2ncia de um bom offboarding.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-38773\" src=\"https:\/\/factorialhr.pt\/wp-content\/uploads\/2021\/02\/como-despedir-funcionario-300x145.png\" alt=\"como despedir um funcionario\" width=\"629\" height=\"304\" srcset=\"https:\/\/factorialhr.com.br\/wp-content\/uploads\/2021\/02\/23154808\/como-despedir-funcionario-300x145.png 300w, https:\/\/factorialhr.com.br\/wp-content\/uploads\/2021\/02\/23154808\/como-despedir-funcionario-768x370.png 768w, https:\/\/factorialhr.com.br\/wp-content\/uploads\/2021\/02\/23154808\/como-despedir-funcionario.png 830w\" sizes=\"(max-width: 629px) 100vw, 629px\" \/><\/p>\n<p><strong>A complexidade de um processo de offboarding geralmente depende de v\u00e1rios fatores:\u00a0<\/strong><\/p>\n<h3><strong>1. O motivo da partida<\/strong><\/h3>\n<p>Quando um funcion\u00e1rio \u00e9 dispensado, algumas etapas do processo assumem mais import\u00e2ncia do que outras. \u00c9 por isso que o processo de offboarding precisar\u00e1 ser adaptado \u00e0s condi\u00e7\u00f5es de cada caso.<\/p>\n<p>Caso o funcion\u00e1rio seja despedido, \u00e9 importante lembrar que nessas ocasi\u00f5es<strong> ter toda a documenta\u00e7\u00e3o e o registos de tudo o que aconteceu<\/strong> ser\u00e1 muito importante para minimizar erros e riscos.<\/p>\n<h3><strong>2. A posi\u00e7\u00e3o do trabalhador<\/strong><\/h3>\n<p><strong>Os funcion\u00e1rios que passaram muito tempo na empresa ter\u00e3o processos de onboarding mais extensos.<\/strong> Isso porque com mais tempo na empresa, provavelmente o RH ter\u00e1 que lidar com um grande n\u00famero de tarefas para encerrar e documentos para verificar. Por isso, planear-se \u00e9 essencial!<\/p>\n<h2><a name=\"2\"><\/a><strong>Por que planear o Offboarding \u00e9 t\u00e3o importante?<\/strong><\/h2>\n<p>O offboarding pode parecer algo \u201cextra\u201d para si, um processo com o qual n\u00e3o devemos &#8220;perder tempo&#8221; porque n\u00e3o afeta a produ\u00e7\u00e3o da empresa, mas \u00e9 o contr\u00e1rio. <strong>Os benef\u00edcios de fazer um bom offboarding s\u00e3o muitos. <\/strong><\/p>\n<p>Al\u00e9m disso, est\u00e1 comprovado que o investimento no processo de offboarding leva a uma maior <a href=\"https:\/\/factorialhr.pt\/blog\/retencao-de-talentos\/\">reten\u00e7\u00e3o de talentos.<\/a> Em suma, um bom plano de offboarding permite que os respons\u00e1veis \u200b\u200bpelos Recursos Humanos facilitem o processo em ambas as partes. Assim, saber como despedir um funcion\u00e1rio n\u00e3o \u00e9 mais t\u00e3o dif\u00edcil assim.<\/p>\n<p><strong>Criar um plano de offboarding \u00e9 crucial. Aqui est\u00e3o as raz\u00f5es para planear-se com anteced\u00eancia:<\/strong><\/p>\n<ul>\n<li><strong>Evita poss\u00edveis perdas financeiras .<\/strong> Sem um plano offboarding, \u00e9 mais prov\u00e1vel que cometa qualquer erro do tipo continuar a pagar benef\u00edcios ou recursos a funcion\u00e1rios que n\u00e3o fazem mais parte da empresa.<\/li>\n<li><strong>Cria uma boa imagem da empresa.<\/strong> &#8220;Ponha fim ao relacionamento&#8221; com o seu trabalhador da melhor maneira poss\u00edvel. Certifique-se de que o talento que sai o fa\u00e7a sentindo-se respeitado e valorizado por seu trabalho.<\/li>\n<li><strong>Melhora a gest\u00e3o jur\u00eddica .<\/strong> Reunir e assinar todos os documentos necess\u00e1rios neste processo \u00e9 fundamental para evitar o risco de reclama\u00e7\u00f5es por despedimento sem justa causa.<\/li>\n<li><strong>Melhora a log\u00edstica .<\/strong> Como ser\u00e3o desempenhadas as fun\u00e7\u00f5es do funcion\u00e1rio que saiu da empresa? Como a equipa ir\u00e1 se organizar at\u00e9 que essa posi\u00e7\u00e3o seja preenchida? Quem vai substituir o funcion\u00e1rio que sai? Essas quest\u00f5es devem ser respondidas no plano de offboarding.<\/li>\n<li><strong>Oportunidade de receber um feedback .<\/strong> Os funcion\u00e1rios que deixam a empresa s\u00e3o uma fonte incr\u00edvel de feedback. Ouvir os motivos da sua sa\u00edda ou apenas a sua opini\u00e3o honesta (mais sincera do que nunca) ajudar\u00e1 a empresa a melhorar no futuro.<\/li>\n<\/ul>\n<h2><a name=\"3\"><\/a><strong>Como despedir um trabalhador: As 11 etapas principais<\/strong><\/h2>\n<p>Despedir um trabalhador nunca \u00e9 f\u00e1cil. Por isso, \u00e9 importante planear-se com anteced\u00eancia. <strong>Definir etapas e tarefas para quando isso acontecer minimiza erros e agiliza todo o processo.<\/strong><\/p>\n<p>Essas etapas podem variar de acordo com cada empresa, o motivo da sa\u00edda do funcion\u00e1rio e o cargo que ocupou na empresa. No entanto, como regra geral, as etapas que destacaremos a seguir tendem a ocorrer em quase todos os processos offboarding. <strong>Confira as 11 etapas principais abaixo:<\/strong><\/p>\n<h3><strong>1. Crie uma lista com caixas de sele\u00e7\u00e3o para o Offboarding<\/strong><\/h3>\n<p>Nosso template inclui todas as etapas que falaremos a seguir, para al\u00e9m de propor perguntas para a conversa de despedimento e uma lista de estoque da empresa <a href=\"#4\"><span style=\"color: #0000ff;\"><strong>(economize tempo e baixe nosso template gr\u00e1tis ).<\/strong><\/span><\/a><\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-38778 \" src=\"https:\/\/factorialhr.pt\/wp-content\/uploads\/2021\/02\/carta-despedimento-300x145.png\" alt=\"carta de despedimento\" width=\"722\" height=\"349\" srcset=\"https:\/\/factorialhr.com.br\/wp-content\/uploads\/2021\/02\/23160252\/carta-despedimento-300x145.png 300w, https:\/\/factorialhr.com.br\/wp-content\/uploads\/2021\/02\/23160252\/carta-despedimento-768x370.png 768w, https:\/\/factorialhr.com.br\/wp-content\/uploads\/2021\/02\/23160252\/carta-despedimento.png 830w\" sizes=\"(max-width: 722px) 100vw, 722px\" \/><\/p>\n<h3><strong>2. Re\u00fana documentos e informa\u00e7\u00f5es<\/strong><\/h3>\n<p>A primeira coisa a se resolver ao receber a not\u00edcia de que um funcion\u00e1rio est\u00e1 deixando a empresa \u00e9 a<strong> assinatura de uma carta de despedimento formal.<\/strong> Em seguida, o gestor ou supervisor de Recursos Humanos pode revisar todos os documentos que o funcion\u00e1rio assinou durante sua perman\u00eancia na empresa. Por exemplo, acordos de confidencialidade podem ter sido estabelecidos no passado, contratos de benef\u00edcios, etc.<\/p>\n<p>Certifique-se de que na carta de despedimento o trabalhador <strong>especifica quando ser\u00e1 o seu \u00faltimo dia na empresa e quando o comunicou (com datas espec\u00edficas).<\/strong><\/p>\n<p>Utilizando um software de gest\u00e3o de Recursos Humanos como o <a href=\"https:\/\/factorialhr.pt\/aplicacoes\">Factorial HR<\/a> , este processo ser\u00e1 muito simples gra\u00e7as \u00e0 sua funcionalidade de<a href=\"https:\/\/factorialhr.pt\/blog\/gestao-documental-hris\/\"> gest\u00e3o documental<\/a> .<\/p>\n<h3><strong>3. Tarefas de contabilidade<\/strong><\/h3>\n<p>Neste ponto, a empresa precisar\u00e1 <strong>lidar com as tarefas cont\u00e1beis<\/strong>, como preparar as informa\u00e7\u00f5es necess\u00e1rias para aplicar as altera\u00e7\u00f5es na declara\u00e7\u00e3o de impostos, programar o \u00faltimo pagamento do sal\u00e1rio, calcular as compensa\u00e7\u00f5es a serem feitas, contabilizar os dias de f\u00e9rias, etc.<\/p>\n<h3><strong>4. Informe a equipa<\/strong><\/h3>\n<p>Em vez de permitir que outros funcion\u00e1rios comecem a ouvir rumores no escrit\u00f3rio, <strong>certifique-se de que todos que ser\u00e3o afetados pelo despedimento de um funcion\u00e1rio saibam da not\u00edcia.<\/strong><\/p>\n<p>Isso geralmente deve ser feito uma semana e meia antes da sa\u00edda do funcion\u00e1rio, dependendo de sua fun\u00e7\u00e3o na equipa. Ap\u00f3s este primeiro aviso, o resto do pessoal pode ser informado.<\/p>\n<p>Por respeito ao trabalhador que vai deixar o emprego, \u00e9 melhor perguntar-lhe como gostaria que a empresa anunciasse a sua sa\u00edda.<\/p>\n<h3><strong>5. Planear a transi\u00e7\u00e3o \u00e9 essencial<\/strong><\/h3>\n<p>O mais importante neste ponto do processo \u00e9 criar um plano para tornar a transi\u00e7\u00e3o do cargo do funcion\u00e1rio o mais suave poss\u00edvel. Este plano deve se concentrar em <strong>concluir as tarefas iniciadas e deixar o terreno pronto para o novo funcion\u00e1rio<\/strong> retomar essas fun\u00e7\u00f5es.<\/p>\n<p>Ser claro sobre como ser\u00e1 essa transi\u00e7\u00e3o e no que vai consistir o trabalho desse funcion\u00e1rio \u00e9 fundamental. Esta \u00e9 a fase em que o conhecimento \u00e9 transferido.<\/p>\n<p><strong>Perguntas que deve responder durante esta transi\u00e7\u00e3o:<\/strong><\/p>\n<ul>\n<li>Quem vai substituir o funcion\u00e1rio?<\/li>\n<li>Que conhecimento ele precisa?<\/li>\n<li>Quem vai treinar o novo trabalhador?<\/li>\n<li>Que projetos precisam ser conclu\u00eddos antes que o funcion\u00e1rio saia?<\/li>\n<li>O que deve passar de um funcion\u00e1rio para outro?<\/li>\n<\/ul>\n<h3><strong>6. Comunica\u00e7\u00e3o com o cliente<\/strong><\/h3>\n<p>Caso o colaborador que est\u00e1 saindo da empresa trabalhe em contato direto com o cliente, \u00e9 muito importante que ele seja avisado e informado dessa mudan\u00e7a. O melhor \u00e9 <strong>fazer isso de forma que o cliente continue a sentir que algu\u00e9m est\u00e1 dispon\u00edvel para ele,<\/strong> apesar de tudo.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-38779\" src=\"https:\/\/factorialhr.pt\/wp-content\/uploads\/2021\/02\/offboarding-guia-300x145.png\" alt=\"offboarding guia\" width=\"683\" height=\"330\" srcset=\"https:\/\/factorialhr.com.br\/wp-content\/uploads\/2021\/02\/23160342\/offboarding-guia-300x145.png 300w, https:\/\/factorialhr.com.br\/wp-content\/uploads\/2021\/02\/23160342\/offboarding-guia-768x370.png 768w, https:\/\/factorialhr.com.br\/wp-content\/uploads\/2021\/02\/23160342\/offboarding-guia.png 830w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/p>\n<h3><strong>7. Recupere o que \u00e9 propriedade da empresa<\/strong><\/h3>\n<p>Durante o tempo em que o funcion\u00e1rio est\u00e1 na empresa, <strong>ele pode ter adquirido equipamentos e materiais que s\u00e3o de propriedade da empresa.<\/strong> Nos \u00faltimos dias antes da sua partida ser\u00e1 preciso recolher esses objetos, que podem ser computadores, telem\u00f3veis, ratos, documento de identidade, uniforme, chaves, alvar\u00e1s de estacionamento ou cart\u00f5es de cr\u00e9dito da empresa, por exemplo.<\/p>\n<p>Nosso modelo inclui uma<strong> lista de invent\u00e1rio da empresa<\/strong> para que n\u00e3o perca tempo com esse processo. <a href=\"#4\"><strong><span style=\"color: #0000ff;\">Descarregue aqui!<\/span><\/strong><\/a><\/p>\n<h3><strong>8. Entrevista de offboarding<\/strong><\/h3>\n<p>O objetivo de uma entrevista de despedimento \u00e9 <strong>obter um feedback valioso sobre a experi\u00eancia que o trabalhador teve dentro da empresa.<\/strong><\/p>\n<p>Esta ser\u00e1 a \u00faltima chance de causar uma impress\u00e3o positiva na pessoa que parte. E tamb\u00e9m ser\u00e1 uma ferramenta de coleta de informa\u00e7\u00f5es que auxiliar\u00e3o a \u00e1rea de Recursos Humanos a tomar melhores decis\u00f5es no futuro.<\/p>\n<p>Fazer as perguntas certas fornecer\u00e1 informa\u00e7\u00f5es valiosas para a empresa, sobre seus pontos fortes e fracos e sobre como melhorar.<\/p>\n<h3><strong>9. Cancelar permiss\u00f5es e contas<\/strong><\/h3>\n<p>Por melhor que seja o seu relacionamento com o trabalhador, por motivos de seguran\u00e7a ele n\u00e3o deve mais ter acesso ao e-mail da empresa, bem como a outras plataformas ou bancos de dados, uma vez que n\u00e3o faz parte da equipa.<\/p>\n<h3><strong>10. Adeus<\/strong><\/h3>\n<p>Independentemente dos motivos da sa\u00edda do funcion\u00e1rio, tentar tornar este momento mais leve \u00e9 sempre uma boa ideia. <strong>Eventos de despedida ou pequenos mimos transmitem positividade por parte da empresa para quem a integrou.<\/strong><\/p>\n<p>Mostre a seu funcion\u00e1rio que valoriza sua contribui\u00e7\u00e3o para a equipa. Isso pode ser feito por meio de um presente, uma carta de agradecimento dedicada de seus colegas ou at\u00e9 mesmo um almo\u00e7o.<\/p>\n<p>No \u00faltimo dia de trabalho do funcion\u00e1rio, \u00e9 aconselh\u00e1vel enviar aviso a todos os funcion\u00e1rios, incentivando-os a se despedirem.<\/p>\n<h3><strong>11. Mantenha a conex\u00e3o ap\u00f3s o offboarding<\/strong><\/h3>\n<p>\u00c9 sempre uma boa ideia n\u00e3o jogar fora nenhum contacto. Por isso, \u00e9 aconselh\u00e1vel <strong>manter uma conex\u00e3o com o ex-funcion\u00e1rio, inclusive por meio de canais como o LinkedIn<\/strong>. Manter um relacionamento positivo nunca \u00e9 demais.<\/p>\n<p><strong>E aqui est\u00e3o as 11 etapas para um processo de desligament<\/strong><strong>o<\/strong>. Se ainda n\u00e3o descarregou o nosso Guia de Offboarding, agora \u00e9 sua vez. \u00c9 gratuito e o ajudar\u00e1 a otimizar ao m\u00e1ximo o processo de sa\u00edda de um funcion\u00e1rio!<a name=\"4\"><\/a><\/p>\n<h3><span style=\"color: #0000ff;\"><strong>\ud83d\udc47 Descarregue o Checklist de Offboarding em Excel\ud83d\udc47\u00a0<\/strong><\/span><\/h3>\n<p><a href=\"https:\/\/factorialhr.pt\/checklists\/offboarding\"><img decoding=\"async\" class=\"alignnone wp-image-39179\" src=\"https:\/\/factorialhr.pt\/wp-content\/uploads\/2021\/02\/checklist-offboarding-300x103.png\" alt=\"checklist offboarding\" width=\"655\" height=\"225\" srcset=\"https:\/\/factorialhr.com.br\/wp-content\/uploads\/2021\/02\/23161640\/checklist-offboarding-300x103.png 300w, https:\/\/factorialhr.com.br\/wp-content\/uploads\/2021\/02\/23161640\/checklist-offboarding-768x263.png 768w, https:\/\/factorialhr.com.br\/wp-content\/uploads\/2021\/02\/23161640\/checklist-offboarding.png 900w\" sizes=\"(max-width: 655px) 100vw, 655px\" \/><\/a><\/p>\n<p>Como j\u00e1 sabe, um bom processo de offboarding pode ser ben\u00e9fico para ambas as partes. Mas muitas vezes \u00e9 dif\u00edcil dar conta de todas as etapas. Ainda que o checklist de offboarding ajude-o, as tarefas ainda devem ser feitas manualmente.<\/p>\n<p>Por isso, contar com um sistema que facilite cada um desses passos pode ser fundamental. <strong>Quer ir al\u00e9m? Automatize v\u00e1rias etapas desse processo com um software de RH como o da Factorial.<\/strong><\/p>\n<h3 style=\"text-align: center;\"><a href=\"https:\/\/factorialhr.pt\/get-started\"><strong><span style=\"color: #0000ff;\">Registe-se e fa\u00e7a o teste por 14 dias gr\u00e1tis. Melhore seus processos de offboarding gra\u00e7as e automatize as tarefas de RH da sua empresa!<\/span><\/strong><\/a><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Quando o RH contrata uma pessoa e acaba de fazer o onboarding dela \u2026 o trabalho j\u00e1 est\u00e1 feito, certo? Na verdade, n\u00e3o. Muitas empresas n\u00e3o d\u00e3o tanta import\u00e2ncia ao processo de offboarding, e \u00e9 muito comum a \u00e1rea de Recursos Humanos focar apenas na parte em que o funcion\u00e1rio \u00e9, propriamente dito, um funcion\u00e1rio.<a href=\"https:\/\/factorialhr.pt\/blog\/guia-de-offboarding\/\" class=\"read-more\"> [&#8230;]<\/a><\/p>\n","protected":false},"author":43,"featured_media":44992,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[398,111],"tags":[],"class_list":["post-38763","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gestao-de-talentos","category-sem-categoria"],"acf":{"topics":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v21.9.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Offboarding: 11 etapas eficazes<\/title>\n<meta name=\"description\" content=\"Offboarding: siga estas 11 etapas para um processo eficaz.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/factorialhr.com.br\/blog\/guia-de-offboarding\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Offboarding: Como despedir um funcion\u00e1rio? [+ Checklist em Excel]\" \/>\n<meta property=\"og:description\" content=\"Offboarding: siga estas 11 etapas para um processo eficaz.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/factorialhr.pt\/blog\/guia-de-offboarding\/\" \/>\n<meta property=\"og:site_name\" content=\"Factorial\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Factorial\/100064908455810\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-24T10:15:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-02T00:43:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/factorialhr.pt\/wp-content\/uploads\/2021\/02\/23172023\/offboarding-funcionario.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1112\" \/>\n\t<meta property=\"og:image:height\" content=\"625\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bruna Carnevale\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@factorialapp\" \/>\n<meta name=\"twitter:site\" content=\"@factorialapp\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bruna Carnevale\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/factorialhr.pt\/blog\/guia-de-offboarding\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/factorialhr.pt\/blog\/guia-de-offboarding\/\"},\"author\":{\"name\":\"Bruna Carnevale\",\"@id\":\"https:\/\/factorialhr.com.br\/blog\/#\/schema\/person\/26636c7e0907348fe1ab59adb41856ba\"},\"headline\":\"Offboarding: Como despedir um funcion\u00e1rio? [+ Checklist em Excel]\",\"datePublished\":\"2021-02-24T10:15:37+00:00\",\"dateModified\":\"2025-06-02T00:43:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/factorialhr.pt\/blog\/guia-de-offboarding\/\"},\"wordCount\":1836,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/factorialhr.com.br\/blog\/#organization\"},\"articleSection\":[\"Gest\u00e3o de Talentos\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/factorialhr.pt\/blog\/guia-de-offboarding\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/factorialhr.pt\/blog\/guia-de-offboarding\/\",\"url\":\"https:\/\/factorialhr.pt\/blog\/guia-de-offboarding\/\",\"name\":\"Offboarding: 11 etapas eficazes\",\"isPartOf\":{\"@id\":\"https:\/\/factorialhr.com.br\/blog\/#website\"},\"datePublished\":\"2021-02-24T10:15:37+00:00\",\"dateModified\":\"2025-06-02T00:43:31+00:00\",\"description\":\"Offboarding: siga estas 11 etapas para um processo eficaz.\",\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/factorialhr.pt\/blog\/guia-de-offboarding\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/factorialhr.com.br\/blog\/#website\",\"url\":\"https:\/\/factorialhr.com.br\/blog\/\",\"name\":\"Factorial\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/factorialhr.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/factorialhr.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/factorialhr.com.br\/blog\/#organization\",\"name\":\"All-in-one business management software - Factorial\",\"url\":\"https:\/\/factorialhr.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/factorialhr.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/factorialhr.com.br\/wp-content\/uploads\/2023\/07\/18155144\/factorial-logo.png\",\"contentUrl\":\"https:\/\/factorialhr.com.br\/wp-content\/uploads\/2023\/07\/18155144\/factorial-logo.png\",\"width\":946,\"height\":880,\"caption\":\"All-in-one business management software - Factorial\"},\"image\":{\"@id\":\"https:\/\/factorialhr.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/people\/Factorial\/100064908455810\/\",\"https:\/\/twitter.com\/factorialapp\",\"https:\/\/www.linkedin.com\/company\/factorialhr\",\"https:\/\/www.youtube.com\/@factorialmedia\",\"https:\/\/www.instagram.com\/factorial\/#\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/factorialhr.com.br\/blog\/#\/schema\/person\/26636c7e0907348fe1ab59adb41856ba\",\"name\":\"Bruna Carnevale\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/factorialhr.com.br\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/45cfba4bcac71b42cf479b28c883ce3f?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/45cfba4bcac71b42cf479b28c883ce3f?s=96&d=identicon&r=g\",\"caption\":\"Bruna Carnevale\"},\"description\":\"Bruna Carnevale \u00e9 Content Manager da Factorial para os mercados do Brasil e Portugal. Com uma forma\u00e7\u00e3o diversa em comunica\u00e7\u00e3o e l\u00ednguas, se diz cada vez mais apaixonada pela \u00e1rea de RH e acredita que o acesso \u00e0 informa\u00e7\u00e3o de qualidade pode ajudar tornar a gest\u00e3o de pessoas cada vez mais humanizada e eficiente.\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/bruna-carnevale\/\"],\"url\":\"https:\/\/factorialhr.com.br\/blog\/author\/bruna\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Offboarding: 11 etapas eficazes","description":"Offboarding: siga estas 11 etapas para um processo eficaz.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/factorialhr.com.br\/blog\/guia-de-offboarding\/","og_locale":"pt_BR","og_type":"article","og_title":"Offboarding: Como despedir um funcion\u00e1rio? [+ Checklist em Excel]","og_description":"Offboarding: siga estas 11 etapas para um processo eficaz.","og_url":"https:\/\/factorialhr.pt\/blog\/guia-de-offboarding\/","og_site_name":"Factorial","article_publisher":"https:\/\/www.facebook.com\/people\/Factorial\/100064908455810\/","article_published_time":"2021-02-24T10:15:37+00:00","article_modified_time":"2025-06-02T00:43:31+00:00","og_image":[{"width":1112,"height":625,"url":"https:\/\/factorialhr.pt\/wp-content\/uploads\/2021\/02\/23172023\/offboarding-funcionario.jpg","type":"image\/jpeg"}],"author":"Bruna Carnevale","twitter_card":"summary_large_image","twitter_creator":"@factorialapp","twitter_site":"@factorialapp","twitter_misc":{"Written by":"Bruna Carnevale","Est. reading time":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/factorialhr.pt\/blog\/guia-de-offboarding\/#article","isPartOf":{"@id":"https:\/\/factorialhr.pt\/blog\/guia-de-offboarding\/"},"author":{"name":"Bruna Carnevale","@id":"https:\/\/factorialhr.com.br\/blog\/#\/schema\/person\/26636c7e0907348fe1ab59adb41856ba"},"headline":"Offboarding: Como despedir um funcion\u00e1rio? [+ Checklist em Excel]","datePublished":"2021-02-24T10:15:37+00:00","dateModified":"2025-06-02T00:43:31+00:00","mainEntityOfPage":{"@id":"https:\/\/factorialhr.pt\/blog\/guia-de-offboarding\/"},"wordCount":1836,"commentCount":1,"publisher":{"@id":"https:\/\/factorialhr.com.br\/blog\/#organization"},"articleSection":["Gest\u00e3o de Talentos"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/factorialhr.pt\/blog\/guia-de-offboarding\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/factorialhr.pt\/blog\/guia-de-offboarding\/","url":"https:\/\/factorialhr.pt\/blog\/guia-de-offboarding\/","name":"Offboarding: 11 etapas eficazes","isPartOf":{"@id":"https:\/\/factorialhr.com.br\/blog\/#website"},"datePublished":"2021-02-24T10:15:37+00:00","dateModified":"2025-06-02T00:43:31+00:00","description":"Offboarding: siga estas 11 etapas para um processo eficaz.","inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/factorialhr.pt\/blog\/guia-de-offboarding\/"]}]},{"@type":"WebSite","@id":"https:\/\/factorialhr.com.br\/blog\/#website","url":"https:\/\/factorialhr.com.br\/blog\/","name":"Factorial","description":"","publisher":{"@id":"https:\/\/factorialhr.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/factorialhr.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/factorialhr.com.br\/blog\/#organization","name":"All-in-one business management software - Factorial","url":"https:\/\/factorialhr.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/factorialhr.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/factorialhr.com.br\/wp-content\/uploads\/2023\/07\/18155144\/factorial-logo.png","contentUrl":"https:\/\/factorialhr.com.br\/wp-content\/uploads\/2023\/07\/18155144\/factorial-logo.png","width":946,"height":880,"caption":"All-in-one business management software - Factorial"},"image":{"@id":"https:\/\/factorialhr.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Factorial\/100064908455810\/","https:\/\/twitter.com\/factorialapp","https:\/\/www.linkedin.com\/company\/factorialhr","https:\/\/www.youtube.com\/@factorialmedia","https:\/\/www.instagram.com\/factorial\/#"]},{"@type":"Person","@id":"https:\/\/factorialhr.com.br\/blog\/#\/schema\/person\/26636c7e0907348fe1ab59adb41856ba","name":"Bruna Carnevale","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/factorialhr.com.br\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/45cfba4bcac71b42cf479b28c883ce3f?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/45cfba4bcac71b42cf479b28c883ce3f?s=96&d=identicon&r=g","caption":"Bruna Carnevale"},"description":"Bruna Carnevale \u00e9 Content Manager da Factorial para os mercados do Brasil e Portugal. Com uma forma\u00e7\u00e3o diversa em comunica\u00e7\u00e3o e l\u00ednguas, se diz cada vez mais apaixonada pela \u00e1rea de RH e acredita que o acesso \u00e0 informa\u00e7\u00e3o de qualidade pode ajudar tornar a gest\u00e3o de pessoas cada vez mais humanizada e eficiente.","sameAs":["https:\/\/www.linkedin.com\/in\/bruna-carnevale\/"],"url":"https:\/\/factorialhr.com.br\/blog\/author\/bruna\/"}]}},"_links":{"self":[{"href":"https:\/\/factorialhr.com.br\/blog\/wp-json\/wp\/v2\/posts\/38763"}],"collection":[{"href":"https:\/\/factorialhr.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/factorialhr.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/factorialhr.com.br\/blog\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/factorialhr.com.br\/blog\/wp-json\/wp\/v2\/comments?post=38763"}],"version-history":[{"count":10,"href":"https:\/\/factorialhr.com.br\/blog\/wp-json\/wp\/v2\/posts\/38763\/revisions"}],"predecessor-version":[{"id":160378,"href":"https:\/\/factorialhr.com.br\/blog\/wp-json\/wp\/v2\/posts\/38763\/revisions\/160378"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/factorialhr.com.br\/blog\/wp-json\/wp\/v2\/media\/44992"}],"wp:attachment":[{"href":"https:\/\/factorialhr.com.br\/blog\/wp-json\/wp\/v2\/media?parent=38763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/factorialhr.com.br\/blog\/wp-json\/wp\/v2\/categories?post=38763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/factorialhr.com.br\/blog\/wp-json\/wp\/v2\/tags?post=38763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}